{"id":9184,"date":"2025-04-16T12:37:20","date_gmt":"2025-04-16T09:37:20","guid":{"rendered":"https:\/\/skamachine.com\/urun\/%d0%bc%d0%b5%d1%82%d1%87%d0%b8%d0%ba-%d1%81-%d1%86%d0%b8%d0%bb%d0%b8%d0%bd%d0%b4%d1%80%d0%b8%d1%87%d0%b5%d1%81%d0%ba%d0%b8%d0%bc-%d1%85%d0%b2%d0%be%d1%81%d1%82%d0%be%d0%b2%d0%b8%d0%ba%d0%be%d0%bc-40\/"},"modified":"2025-04-16T12:37:20","modified_gmt":"2025-04-16T09:37:20","slug":"%d0%bc%d0%b5%d1%82%d1%87%d0%b8%d0%ba-%d1%81-%d1%86%d0%b8%d0%bb%d0%b8%d0%bd%d0%b4%d1%80%d0%b8%d1%87%d0%b5%d1%81%d0%ba%d0%b8%d0%bc-%d1%85%d0%b2%d0%be%d1%81%d1%82%d0%be%d0%b2%d0%b8%d0%ba%d0%be%d0%bc-40","status":"publish","type":"product","link":"https:\/\/skamachine.com\/ru\/urun\/%d0%bc%d0%b5%d1%82%d1%87%d0%b8%d0%ba-%d1%81-%d1%86%d0%b8%d0%bb%d0%b8%d0%bd%d0%b4%d1%80%d0%b8%d1%87%d0%b5%d1%81%d0%ba%d0%b8%d0%bc-%d1%85%d0%b2%d0%be%d1%81%d1%82%d0%be%d0%b2%d0%b8%d0%ba%d0%be%d0%bc-40\/","title":{"rendered":"\u041c\u0435\u0442\u0447\u0438\u043a \u0441 \u0446\u0438\u043b\u0438\u043d\u0434\u0440\u0438\u0447\u0435\u0441\u043a\u0438\u043c \u0445\u0432\u043e\u0441\u0442\u043e\u0432\u0438\u043a\u043e\u043c 40\u00d7430"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-6079 size-full\" src=\"http:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/Silindirik-Saftli-Kilavuz-Cekme-40x430-Tablo-Urun.jpeg\" alt=\"\" width=\"842\" height=\"142\" srcset=\"https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/Silindirik-Saftli-Kilavuz-Cekme-40x430-Tablo-Urun.jpeg 842w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/Silindirik-Saftli-Kilavuz-Cekme-40x430-Tablo-Urun-300x51.jpeg 300w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/Silindirik-Saftli-Kilavuz-Cekme-40x430-Tablo-Urun-768x130.jpeg 768w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/Silindirik-Saftli-Kilavuz-Cekme-40x430-Tablo-Urun-600x101.jpeg 600w\" sizes=\"(max-width: 842px) 100vw, 842px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-6079 size-full\" src=\"http:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/Silindirik-Saftli-Kilavuz-Cekme-40x430-Tablo-Urun.jpeg\" alt=\"\" width=\"842\" height=\"142\" srcset=\"https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/Silindirik-Saftli-Kilavuz-Cekme-40x430-Tablo-Urun.jpeg 842w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/Silindirik-Saftli-Kilavuz-Cekme-40x430-Tablo-Urun-300x51.jpeg 300w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/Silindirik-Saftli-Kilavuz-Cekme-40x430-Tablo-Urun-768x130.jpeg 768w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/Silindirik-Saftli-Kilavuz-Cekme-40x430-Tablo-Urun-600x101.jpeg 600w\" sizes=\"(max-width: 842px) 100vw, 842px\" \/><\/p>\n","protected":false},"featured_media":9185,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[211],"product_tag":[],"class_list":{"0":"post-9184","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat--sspb-sst","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/skamachine.com\/ru\/wp-json\/wp\/v2\/product\/9184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skamachine.com\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/skamachine.com\/ru\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/skamachine.com\/ru\/wp-json\/wp\/v2\/comments?post=9184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skamachine.com\/ru\/wp-json\/wp\/v2\/media\/9185"}],"wp:attachment":[{"href":"https:\/\/skamachine.com\/ru\/wp-json\/wp\/v2\/media?parent=9184"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/skamachine.com\/ru\/wp-json\/wp\/v2\/product_brand?post=9184"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/skamachine.com\/ru\/wp-json\/wp\/v2\/product_cat?post=9184"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/skamachine.com\/ru\/wp-json\/wp\/v2\/product_tag?post=9184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}