{"id":9398,"date":"2025-04-16T12:24:52","date_gmt":"2025-04-16T09:24:52","guid":{"rendered":"https:\/\/skamachine.com\/urun\/sk-50-standard-veldon-holder\/"},"modified":"2025-04-16T12:24:52","modified_gmt":"2025-04-16T09:24:52","slug":"sk-50-standard-veldon-holder","status":"publish","type":"product","link":"https:\/\/skamachine.com\/en\/urun\/sk-50-standard-veldon-holder\/","title":{"rendered":"SK-50 Standard Veldon Holder"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-2482 size-full\" src=\"http:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/sk-50-standart-veldon-1.webp\" alt=\"\" width=\"1987\" height=\"857\" srcset=\"https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/sk-50-standart-veldon-1.webp 1987w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/sk-50-standart-veldon-1-600x259.webp 600w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/sk-50-standart-veldon-1-300x129.webp 300w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/sk-50-standart-veldon-1-1024x442.webp 1024w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/sk-50-standart-veldon-1-768x331.webp 768w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/sk-50-standart-veldon-1-1536x662.webp 1536w\" sizes=\"(max-width: 1987px) 100vw, 1987px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-2482 size-full\" src=\"http:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/sk-50-standart-veldon-1.webp\" alt=\"\" width=\"1987\" height=\"857\" srcset=\"https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/sk-50-standart-veldon-1.webp 1987w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/sk-50-standart-veldon-1-600x259.webp 600w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/sk-50-standart-veldon-1-300x129.webp 300w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/sk-50-standart-veldon-1-1024x442.webp 1024w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/sk-50-standart-veldon-1-768x331.webp 768w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/sk-50-standart-veldon-1-1536x662.webp 1536w\" sizes=\"(max-width: 1987px) 100vw, 1987px\" \/><\/p>\n","protected":false},"featured_media":9399,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[264],"product_tag":[],"class_list":{"0":"post-9398","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sk-group","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/skamachine.com\/en\/wp-json\/wp\/v2\/product\/9398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skamachine.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/skamachine.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/skamachine.com\/en\/wp-json\/wp\/v2\/comments?post=9398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skamachine.com\/en\/wp-json\/wp\/v2\/media\/9399"}],"wp:attachment":[{"href":"https:\/\/skamachine.com\/en\/wp-json\/wp\/v2\/media?parent=9398"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/skamachine.com\/en\/wp-json\/wp\/v2\/product_brand?post=9398"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/skamachine.com\/en\/wp-json\/wp\/v2\/product_cat?post=9398"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/skamachine.com\/en\/wp-json\/wp\/v2\/product_tag?post=9398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}