{"id":9262,"date":"2025-04-16T12:31:41","date_gmt":"2025-04-16T09:31:41","guid":{"rendered":"https:\/\/skamachine.com\/urun\/iso-veldon-holder\/"},"modified":"2025-04-16T12:31:41","modified_gmt":"2025-04-16T09:31:41","slug":"iso-veldon-holder","status":"publish","type":"product","link":"https:\/\/skamachine.com\/en\/urun\/iso-veldon-holder\/","title":{"rendered":"ISO Veldon Holder"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-2473 size-full\" src=\"http:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/iso-veldon-1.webp\" alt=\"\" width=\"1971\" height=\"794\" srcset=\"https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/iso-veldon-1.webp 1971w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/iso-veldon-1-600x242.webp 600w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/iso-veldon-1-300x121.webp 300w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/iso-veldon-1-1024x413.webp 1024w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/iso-veldon-1-768x309.webp 768w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/iso-veldon-1-1536x619.webp 1536w\" sizes=\"(max-width: 1971px) 100vw, 1971px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-2473 size-full\" src=\"http:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/iso-veldon-1.webp\" alt=\"\" width=\"1971\" height=\"794\" srcset=\"https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/iso-veldon-1.webp 1971w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/iso-veldon-1-600x242.webp 600w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/iso-veldon-1-300x121.webp 300w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/iso-veldon-1-1024x413.webp 1024w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/iso-veldon-1-768x309.webp 768w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/iso-veldon-1-1536x619.webp 1536w\" sizes=\"(max-width: 1971px) 100vw, 1971px\" \/><\/p>\n","protected":false},"featured_media":9263,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[259],"product_tag":[],"class_list":{"0":"post-9262","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-iso-group","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/skamachine.com\/en\/wp-json\/wp\/v2\/product\/9262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skamachine.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/skamachine.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/skamachine.com\/en\/wp-json\/wp\/v2\/comments?post=9262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skamachine.com\/en\/wp-json\/wp\/v2\/media\/9263"}],"wp:attachment":[{"href":"https:\/\/skamachine.com\/en\/wp-json\/wp\/v2\/media?parent=9262"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/skamachine.com\/en\/wp-json\/wp\/v2\/product_brand?post=9262"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/skamachine.com\/en\/wp-json\/wp\/v2\/product_cat?post=9262"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/skamachine.com\/en\/wp-json\/wp\/v2\/product_tag?post=9262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}