{"id":8506,"date":"2025-04-21T10:31:44","date_gmt":"2025-04-21T07:31:44","guid":{"rendered":"https:\/\/skamachine.com\/urun\/%d8%b5%d8%a7%d9%85%d9%88%d9%84%d8%a9-%d8%b8%d8%b1%d9%81-%d8%aa%d8%ac%d9%85%d9%8a%d8%b9%d9%8a-%d8%b3%d9%84%d8%b3%d9%84%d8%a9-er-%d8%b1%d9%82%d9%85-3\/"},"modified":"2025-04-21T10:31:44","modified_gmt":"2025-04-21T07:31:44","slug":"%d8%b5%d8%a7%d9%85%d9%88%d9%84%d8%a9-%d8%b8%d8%b1%d9%81-%d8%aa%d8%ac%d9%85%d9%8a%d8%b9%d9%8a-%d8%b3%d9%84%d8%b3%d9%84%d8%a9-er-%d8%b1%d9%82%d9%85-3","status":"publish","type":"product","link":"https:\/\/skamachine.com\/ar\/urun\/%d8%b5%d8%a7%d9%85%d9%88%d9%84%d8%a9-%d8%b8%d8%b1%d9%81-%d8%aa%d8%ac%d9%85%d9%8a%d8%b9%d9%8a-%d8%b3%d9%84%d8%b3%d9%84%d8%a9-er-%d8%b1%d9%82%d9%85-3\/","title":{"rendered":"\u0635\u0627\u0645\u0648\u0644\u0629 \u0638\u0631\u0641 \u062a\u062c\u0645\u064a\u0639\u064a \u0633\u0644\u0633\u0644\u0629 ER \u0631\u0642\u0645 3"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-2449 size-full\" src=\"http:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/er-serisi-pens-kapaklari.webp\" alt=\"\" width=\"1573\" height=\"568\" srcset=\"https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/er-serisi-pens-kapaklari.webp 1573w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/er-serisi-pens-kapaklari-600x217.webp 600w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/er-serisi-pens-kapaklari-300x108.webp 300w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/er-serisi-pens-kapaklari-1024x370.webp 1024w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/er-serisi-pens-kapaklari-768x277.webp 768w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/er-serisi-pens-kapaklari-1536x555.webp 1536w\" sizes=\"(max-width: 1573px) 100vw, 1573px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-2449 size-full\" src=\"http:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/er-serisi-pens-kapaklari.webp\" alt=\"\" width=\"1573\" height=\"568\" srcset=\"https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/er-serisi-pens-kapaklari.webp 1573w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/er-serisi-pens-kapaklari-600x217.webp 600w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/er-serisi-pens-kapaklari-300x108.webp 300w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/er-serisi-pens-kapaklari-1024x370.webp 1024w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/er-serisi-pens-kapaklari-768x277.webp 768w, https:\/\/skamachine.com\/wp-content\/uploads\/2025\/04\/er-serisi-pens-kapaklari-1536x555.webp 1536w\" sizes=\"(max-width: 1573px) 100vw, 1573px\" \/><\/p>\n","protected":false},"featured_media":8507,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[218],"product_tag":[],"class_list":{"0":"post-8506","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-218","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/skamachine.com\/ar\/wp-json\/wp\/v2\/product\/8506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skamachine.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/skamachine.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/skamachine.com\/ar\/wp-json\/wp\/v2\/comments?post=8506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skamachine.com\/ar\/wp-json\/wp\/v2\/media\/8507"}],"wp:attachment":[{"href":"https:\/\/skamachine.com\/ar\/wp-json\/wp\/v2\/media?parent=8506"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/skamachine.com\/ar\/wp-json\/wp\/v2\/product_brand?post=8506"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/skamachine.com\/ar\/wp-json\/wp\/v2\/product_cat?post=8506"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/skamachine.com\/ar\/wp-json\/wp\/v2\/product_tag?post=8506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}